{"id":21319,"date":"2019-02-06T13:53:34","date_gmt":"2019-02-06T13:53:34","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/ppmv-100\/"},"modified":"2026-05-07T13:09:43","modified_gmt":"2026-05-07T13:09:43","slug":"ppfc-100","status":"publish","type":"page","link":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/","title":{"rendered":"PPFC-100"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Header&#8221; module_class=&#8221;header-top-sub&#8221; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;130deg&#8221; background_color_gradient_stops=&#8221;#352597 0%|#8686FF 100%&#8221; background_color_gradient_start=&#8221;#352597&#8243; background_color_gradient_end=&#8221;#8686FF&#8221; background_image=&#8221;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/02\/background-header-nologo.png&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;0||100px||false|false&#8221; custom_padding_tablet=&#8221;100px||100px||true&#8221; custom_padding_phone=&#8221;||||true&#8221; bottom_divider_height=&#8221;250px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_height_tablet=&#8221;150px&#8221; bottom_divider_height_phone=&#8221;110px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; bottom_divider_color=&#8221;#0c71c3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code _builder_version=&#8221;3.14&#8243; global_module=&#8221;339&#8243; global_colors_info=&#8221;{}&#8221;]<span><span><a href=\"https:\/\/rhtc-workshoppress.com\/pt-pt\/\">Home<\/a><\/span><\/span>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;4px|0px|27px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_class=&#8221;product-name&#8221; _builder_version=&#8221;4.21.0&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; header_2_font=&#8221;Roboto|700|||||||&#8221; header_2_font_size=&#8221;45px&#8221; header_2_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;800px&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Prensa de 4 Colunas de 100 Toneladas: PPFC-100<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;2px|0px|54px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/Four-Column-Press-Profi-Press-PPFC-Model-scaled.jpg&#8221; alt=&#8221;Prensa de Quatro Colunas &#8211; Profi Press&#8221; title_text=&#8221;Prensa de Quatro Colunas &#8211; Profi Press&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; module_class=&#8221;zoooom&#8221; _builder_version=&#8221;4.21.0&#8243; max_width=&#8221;75{cac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c774}&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Esta <em><strong>Prensa de 4 Colunas de 100 Toneladas<\/strong><\/em> \u00e9 fabricada com 4 colunas cil\u00edndricas para assegurar o perfeito paralelismo da mesa superior. Recomendamos este tipo de prensa hidr\u00e1ulica para trabalhos que exijam elevada precis\u00e3o ou para tarefas especiais de prensagem.<\/p>\n<p style=\"text-align: justify;\">Profi Press four column presses have a manual or automatic mode and the presses work with 2 different cylinder speeds. With the NC-control you can digitally set the pressure, piston stroke, holding time and save up to 100 different working cycles. Furthermore, these models are operated by an electric foot pedal.  <\/p>\n<p style=\"text-align: justify;\">Todas as nossas prensas hidr\u00e1ulicas est\u00e3o em conformidade com as normas CE e fabricamo-las apenas com componentes de alta qualidade para garantir uma grande durabilidade. A nossa prensa de 4 colunas de 100 toneladas \u00e9 fabricada na Europa e garantimos a alta qualidade desta prensa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/rhtc-workshoppress.com\/pt-pt\/contacto\/\">Contacte-nos para mais informa\u00e7\u00e3o <\/a> ou solicite um or\u00e7amento atrav\u00e9s do bot\u00e3o abaixo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/rhtc-workshoppress.com\/pt-pt\/orcamentos\/&#8221; button_text=&#8221;Pe\u00e7a um or\u00e7amento&#8221; button_alignment=&#8221;center&#8221; module_class=&#8221;quotation-button&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;13px&#8221; button_bg_color=&#8221;#f48004&#8243; button_bg_color_gradient_direction=&#8221;90deg&#8221; button_bg_color_gradient_stops=&#8221;#00f264 0%|#fcb6ab 100%&#8221; button_bg_color_gradient_start=&#8221;#00f264&#8243; button_bg_color_gradient_end=&#8221;#fcb6ab&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;4px&#8221; button_letter_spacing=&#8221;5px&#8221; button_font=&#8221;Roboto|700||on|||||&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;18px|34px|18px|34px|true|true&#8221; button_letter_spacing_hover=&#8221;5.5px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;5.5px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; bottom_divider_color=&#8221;#0c71c3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;1440px&#8221; custom_padding=&#8221;27px|0px|0|0px|false|false&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;1440px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong>Especifica\u00e7\u00f5es t\u00e9cnicas desta Prensa de 4 Colunas de 100 Toneladas<\/strong><\/h6>\n<ul>\n<li>For\u00e7a [tn]: 100<\/li>\n<li>Pot\u00eancia do motor [kW]: 7,5<\/li>\n<li>Velocidade de funcionamento [mm\/sec]: 7<\/li>\n<li>Velocidade de aproxima\u00e7\u00e3o [mm\/s]: 32,4<\/li>\n<li>Velocidade de retorno [mm\/s]: 46,2<\/li>\n<li>Curso do pist\u00e3o [mm]: 460<\/li>\n<li>Di\u00e2metro da coluna [mm]: 100<\/li>\n<li>Dimens\u00f5es da mesa [mm]: 1460 x 1020<\/li>\n<li>Entre colunas [mm]: 1060 x 660<\/li>\n<li>Altura [mm]: 680<\/li>\n<li>Altura de funcionamento [mm]: 800<\/li>\n<li>Comprimento total (lateral) [mm]: 1520<\/li>\n<li>Largura total (frontal) [mm]: 2020<\/li>\n<li>Altura total [mm]: 2460<\/li>\n<li>Peso [mm]: 5600<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h6><strong>Carater\u00edsticas do PPFC-100<\/strong><\/h6>\n<ul>\n<li>Estrutura da m\u00e1quina r\u00edgida e robusta<\/li>\n<li>Mesas superior e inferior com ranhuras em T<\/li>\n<li>Quatro colunas cil\u00edndricas para um paralelismo perfeito<\/li>\n<li>Regula\u00e7\u00e3o digital e memoriza\u00e7\u00e3o dos par\u00e2metros<\/li>\n<li>Seletor para modo manual\/autom\u00e1tico<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6><strong>Acess\u00f3rios opcionais<\/strong><\/h6>\n<ul>\n<li>Mesa inferior frontal deslizante<\/li>\n<li>Adapta\u00e7\u00f5es para rob\u00f3tica<\/li>\n<li>Conex\u00f5es hidr\u00e1ulicas para sistemas perif\u00e9ricos<\/li>\n<li>Velocidades elevadas atrav\u00e9s de v\u00e1lvulas preenchidas e cilindros auxiliares<\/li>\n<li>Amortecedor hidr\u00e1ulico ou ejector<\/li>\n<li>Sistema de arrefecimento para o grupo hidr\u00e1ulico atrav\u00e9s de um sistema de ar \/ \u00f3leo<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, esta prensa de 4 colunas e 100 toneladas podem ser adaptadas a requisitos espec\u00edficos como uma maior passagem do pist\u00e3o ou mesas maiores, por exemplo.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UCY9jkO8W5-KsthszYTC_MNg?view_as=subscriber\" target=\"_blank\" rel=\"noopener noreferrer\">Para v\u00eddeos das nossas m\u00e1quinas, v\u00e1 ao nosso YouTube-Channel!<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong>Dimens\u00f5es<\/strong><\/h6>\n<ul>\n<li>A x B: 1020 x 1460 mm<\/li>\n<li>C x D: 660 x 1060 mm<\/li>\n<li>V: 680 mm<\/li>\n<li>F: 800 mm<\/li>\n<li>L: 1520 mm<\/li>\n<li>W: 2020 mm<\/li>\n<li>H: 2460 mm<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/Four-Column-Press-Drawing-with-Dimensions.png&#8221; title_text=&#8221;Prensa de quatro colunas &#8211; Desenho com dimens\u00f5es&#8221; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; prev_background_color=&#8221;#ffffff&#8221; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;130deg&#8221; background_color_gradient_stops=&#8221;#352597 0%|#8686FF 100%&#8221; background_color_gradient_start=&#8221;#352597&#8243; background_color_gradient_end=&#8221;#8686FF&#8221; background_image=&#8221;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2018\/09\/below.jpg&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;9vw||50px||false|false&#8221; custom_padding_tablet=&#8221;100px||100px||true&#8221; custom_padding_phone=&#8221;||||true&#8221; top_divider_style=&#8221;ramp&#8221; top_divider_height=&#8221;250px&#8221; top_divider_flip=&#8221;vertical&#8221; top_divider_height_tablet=&#8221;150px&#8221; top_divider_height_phone=&#8221;110px&#8221; top_divider_height_last_edited=&#8221;on|phone&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;80%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_margin_phone=&#8221;|||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;|||&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Roboto|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_3_font=&#8221;Roboto|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#ffffff&#8221; header_3_font_size=&#8221;24px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;850px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;32px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;16px&#8221; header_3_font_size_phone=&#8221;14px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><\/h3>\n<h2>\u2018 PRENSAS QUE MARCAM \u2018<\/h2>\n<h3>Entrar em contacto<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/rhtc-workshoppress.com\/pt-pt\/contacto\/&#8221; button_text=&#8221;Contacte-nos&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;13px&#8221; button_bg_color=&#8221;#f48004&#8243; button_bg_color_gradient_direction=&#8221;90deg&#8221; button_bg_color_gradient_stops=&#8221;#00f264 0%|#fcb6ab 100%&#8221; button_bg_color_gradient_start=&#8221;#00f264&#8243; button_bg_color_gradient_end=&#8221;#fcb6ab&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;4px&#8221; button_letter_spacing=&#8221;5px&#8221; button_font=&#8221;Roboto|700||on|||||&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;18px|34px|18px|34px|true|true&#8221; button_letter_spacing_hover=&#8221;5.5px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;5.5px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span><span><a href=\"https:\/\/rhtc-workshoppress.com\/pt-pt\/\">Home<\/a><\/span><\/span>Prensa de 4 Colunas de 100 Toneladas: PPFC-100Esta Prensa de 4 Colunas de 100 Toneladas \u00e9 fabricada com 4 colunas cil\u00edndricas para assegurar o perfeito paralelismo da mesa superior. Recomendamos este tipo de prensa hidr\u00e1ulica para trabalhos que exijam elevada precis\u00e3o ou para tarefas especiais de prensagem. Profi Press four column presses have a manual [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":21785,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-21319","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press<\/title>\n<meta name=\"description\" content=\"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press\" \/>\n<meta property=\"og:description\" content=\"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T13:09:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/ppfc-100\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/ppfc-100\\\/\",\"name\":\"Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2019-02-06T13:53:34+00:00\",\"dateModified\":\"2026-05-07T13:09:43+00:00\",\"description\":\"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/ppfc-100\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/ppfc-100\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/ppfc-100\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prensas de quatro colunas\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/produtos\\\/prensas-quatro-colunas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PPFC-100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press","description":"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/","og_locale":"pt_PT","og_type":"article","og_title":"Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press","og_description":"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!","og_url":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/","og_site_name":"RHTC","article_modified_time":"2026-05-07T13:09:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/","url":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/","name":"Prensa de 4 Colunas de 100 Toneladas | PPFC-100 | Profi Press","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#website"},"datePublished":"2019-02-06T13:53:34+00:00","dateModified":"2026-05-07T13:09:43+00:00","description":"A nossa prensa de 4 colunas de 100 toneladas \u00e9 perfeita para tarefas que exigem elevada precis\u00e3o e paralelismo. Fabricada na Europa, com alta qualidade garantida!","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/ppfc-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/"},{"@type":"ListItem","position":3,"name":"Prensas de quatro colunas","item":"https:\/\/rhtc-workshoppress.com\/pt-pt\/produtos\/prensas-quatro-colunas\/"},{"@type":"ListItem","position":4,"name":"PPFC-100"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#website","url":"https:\/\/rhtc-workshoppress.com\/pt-pt\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/pages\/21319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=21319"}],"version-history":[{"count":17,"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/pages\/21319\/revisions"}],"predecessor-version":[{"id":42252,"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/pages\/21319\/revisions\/42252"}],"up":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/pages\/21785"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=21319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}