{"id":35243,"date":"2024-08-01T12:13:08","date_gmt":"2024-08-01T12:13:08","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/nouveau-bureau-de-vente-rhtc-en-espagne\/"},"modified":"2024-08-01T13:53:21","modified_gmt":"2024-08-01T13:53:21","slug":"nouveau-bureau-de-vente-rhtc-en-espagne","status":"publish","type":"post","link":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/","title":{"rendered":"Nouveau bureau de vente RHTC en Espagne"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Apr\u00e8s avoir lanc\u00e9 RHTC au Royaume-Uni, au Portugal et en France, nous sommes heureux d&rsquo;annoncer la cr\u00e9ation d&rsquo;un nouveau bureau en Espagne : RHTC Spain ! Mucho Gusto ! \u2764\ufe0f  <\/p>\n<p>Nous avons tout ce qu&rsquo;il faut dans notre usine pour r\u00e9pondre aux exigences de nos clients en Espagne et dans tous les autres pays hispanophones. Nous sommes \u00e0 leur enti\u00e8re disposition via <a class=\"app-aware-link \" href=\"mailto:info@rhtc.es\" target=\"_self\" data-test-app-aware-link=\"\" rel=\"noopener\">info@rhtc.es<\/a> en espagnol bien s\u00fbr ! Notre site web est traduit <a href=\"https:\/\/rhtc-workshoppress.com\/es\/\" target=\"_blank\" rel=\"noopener\">en espagnol<\/a> depuis un certain temps d\u00e9j\u00e0 et nous avons constat\u00e9 un grand int\u00e9r\u00eat pour nos presses hydrauliques Profi Press de haute qualit\u00e9 &#8211; il est donc temps de nous d\u00e9velopper !<\/p>\n<p>  <\/p>\n<p>En plus de nos clients existants en Espagne et en Am\u00e9rique du Sud et Centrale, nous d\u00e9veloppons \u00e9galement notre r\u00e9seau de revendeurs dans ces pays. Pour l&rsquo;instant, nous avons plusieurs r\u00e9unions (en ligne jusqu&rsquo;\u00e0 pr\u00e9sent ) avec certains revendeurs dans ces pays \u00e9galement. <\/p>\n<p>N&rsquo;h\u00e9sitez donc pas \u00e0 nous contacter \u00e0 l&rsquo;adresse <a class=\"app-aware-link \" href=\"mailto:info@rhtc.es\" target=\"_self\" data-test-app-aware-link=\"\" rel=\"noopener\">info@rhtc.es<\/a> et laissez-vous surprendre par nos presses hydrauliques Profi Press de haute qualit\u00e9, livr\u00e9es rapidement, standard ou personnalis\u00e9es !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35179 size-MB-product-image\" src=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png\" alt=\"RHTC Espagne\" width=\"575\" height=\"575\"><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir lanc\u00e9 RHTC au Royaume-Uni, au Portugal et en France, nous sommes heureux d&rsquo;annoncer la cr\u00e9ation d&rsquo;un nouveau bureau en Espagne : RHTC Spain ! Mucho Gusto ! \u2764\ufe0f Nous avons tout ce qu&rsquo;il faut dans notre usine pour r\u00e9pondre aux exigences de nos clients en Espagne et dans tous les autres pays hispanophones. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[556],"tags":[],"class_list":["post-35243","post","type-post","status-publish","format-standard","hentry","category-blogs-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveau bureau de vente RHTC en Espagne | RHTC<\/title>\n<meta name=\"description\" content=\"Nous sommes heureux d&#039;annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveau bureau de vente RHTC en Espagne | RHTC\" \/>\n<meta property=\"og:description\" content=\"Nous sommes heureux d&#039;annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-01T12:13:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-01T13:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png\" \/>\n<meta name=\"author\" content=\"RHTC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"RHTC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/\"},\"author\":{\"name\":\"RHTC\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\"},\"headline\":\"Nouveau bureau de vente RHTC en Espagne\",\"datePublished\":\"2024-08-01T12:13:08+00:00\",\"dateModified\":\"2024-08-01T13:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/RHTC-office-Spain-575x575.png\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/\",\"name\":\"Nouveau bureau de vente RHTC en Espagne | RHTC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/RHTC-office-Spain-575x575.png\",\"datePublished\":\"2024-08-01T12:13:08+00:00\",\"dateModified\":\"2024-08-01T13:53:21+00:00\",\"description\":\"Nous sommes heureux d'annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/RHTC-office-Spain-575x575.png\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/RHTC-office-Spain-575x575.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/nouveau-bureau-de-vente-rhtc-en-espagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveau bureau de vente RHTC en Espagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\",\"name\":\"RHTC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"caption\":\"RHTC\"},\"sameAs\":[\"http:\\\/\\\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveau bureau de vente RHTC en Espagne | RHTC","description":"Nous sommes heureux d'annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveau bureau de vente RHTC en Espagne | RHTC","og_description":"Nous sommes heureux d'annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !","og_url":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/","og_site_name":"RHTC","article_published_time":"2024-08-01T12:13:08+00:00","article_modified_time":"2024-08-01T13:53:21+00:00","og_image":[{"url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png","type":"","width":"","height":""}],"author":"RHTC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"RHTC","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#article","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/"},"author":{"name":"RHTC","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/person\/fadd73d310be137e9255b99017752b02"},"headline":"Nouveau bureau de vente RHTC en Espagne","datePublished":"2024-08-01T12:13:08+00:00","dateModified":"2024-08-01T13:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/"},"wordCount":260,"publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png","articleSection":["Blogs"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/","url":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/","name":"Nouveau bureau de vente RHTC en Espagne | RHTC","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#primaryimage"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png","datePublished":"2024-08-01T12:13:08+00:00","dateModified":"2024-08-01T13:53:21+00:00","description":"Nous sommes heureux d'annoncer la cr\u00e9ation de RHTC ESPAGNE ! Nous avons un nouveau bureau de vente en Espagne pour servir tous nos clients espagnols (et hispanophones) !","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#primaryimage","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/08\/RHTC-office-Spain-575x575.png"},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/fr\/nouveau-bureau-de-vente-rhtc-en-espagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveau bureau de vente RHTC en Espagne"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#website","url":"https:\/\/rhtc-workshoppress.com\/fr\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/person\/fadd73d310be137e9255b99017752b02","name":"RHTC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","caption":"RHTC"},"sameAs":["http:\/\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server"]}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/35243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/comments?post=35243"}],"version-history":[{"count":2,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/35243\/revisions"}],"predecessor-version":[{"id":35245,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/35243\/revisions\/35245"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/media?parent=35243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/categories?post=35243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/tags?post=35243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}