{"id":26367,"date":"2019-09-18T14:42:07","date_gmt":"2019-09-18T14:42:07","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/visite-de-lemo-hannover-2019\/"},"modified":"2022-03-04T11:16:28","modified_gmt":"2022-03-04T11:16:28","slug":"visite-de-lemo-hannover-2019","status":"publish","type":"post","link":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/","title":{"rendered":"Visiter l&rsquo;EMO de Hanovre"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.20.2&Prime;][et_pb_row _builder_version=\u00a0\u00bb3.20.2&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.20.2&Prime;][et_pb_text _builder_version=\u00a0\u00bb3.20.2&Prime;]<\/p>\n<p>Nos coll\u00e8gues Rob et Tim Huberts visitent l&rsquo;<a href=\"https:\/\/www.emo-hannover.de\/en\" target=\"_blank\" rel=\"noopener noreferrer\">EMO \u00e0 Hanovre<\/a> aujourd&rsquo;hui et demain. C&rsquo;est l&rsquo;une des plus grandes expositions pour l&rsquo;industrie du travail du m\u00e9tal et c&rsquo;est une exposition tr\u00e8s int\u00e9ressante pour nous !<\/p>\n<p>RHTC essaie toujours de participer \u00e0 cette exposition pour soutenir les revendeurs qui pr\u00e9sentent nos presses ou pour rencontrer de nouveaux partenaires commerciaux potentiels. De nombreux visiteurs de l&rsquo;EMO proviennent de secteurs industriels auxquels nous fournissons nos presses, l&rsquo;<a href=\"https:\/\/rhtc-workshoppress.com\/branches\/\" target=\"_blank\" rel=\"noopener noreferrer\">industrie automobile<\/a> par exemple ou le <a href=\"https:\/\/rhtc-workshoppress.com\/fr\/produits\/presses-sur-mesure\/ligne-de-production\/\" target=\"_blank\" rel=\"noopener noreferrer\">secteur a\u00e9rospatial<\/a>. C&rsquo;est donc toujours une bonne id\u00e9e pour nous de visiter le parc des expositions de Hanovre pendant quelques jours au cours de l&rsquo;EMO.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4799 size-medium aligncenter\" src=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\"><\/p>\n<p>Vous souhaitez prendre contact et organiser un rendez-vous pendant l&rsquo;exposition ? Appelez-nous et nous arrangerons cela imm\u00e9diatement !<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos coll\u00e8gues Rob et Tim Huberts visitent l&rsquo;EMO \u00e0 Hanovre aujourd&rsquo;hui et demain. C&rsquo;est l&rsquo;une des plus grandes expositions pour l&rsquo;industrie du travail du m\u00e9tal et c&rsquo;est une exposition tr\u00e8s int\u00e9ressante pour nous ! RHTC essaie toujours de participer \u00e0 cette exposition pour soutenir les revendeurs qui pr\u00e9sentent nos presses ou pour rencontrer de nouveaux [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[20],"tags":[71,77,670,674,672,578,585,40,671],"class_list":["post-26367","post","type-post","status-publish","format-standard","hentry","category-blogs","tag-emo-hannover","tag-emo-hannover-2019","tag-exposition-de-hanovre","tag-foire-industrielle","tag-industrie-du-travail-des-metaux","tag-machines-a-travailler-le-metal","tag-presses-hydrauliques","tag-profi-press","tag-salon-dhanovre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visiter l&#039;EMO de Hanovre | RHTC<\/title>\n<meta name=\"description\" content=\"RHTC visite l&#039;EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l&#039;industrie m\u00e9tallurgique !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visiter l&#039;EMO de Hanovre | RHTC\" \/>\n<meta property=\"og:description\" content=\"RHTC visite l&#039;EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l&#039;industrie m\u00e9tallurgique !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T14:42:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-04T11:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg\" \/>\n<meta name=\"author\" content=\"RHTC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"RHTC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/\"},\"author\":{\"name\":\"RHTC\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\"},\"headline\":\"Visiter l&rsquo;EMO de Hanovre\",\"datePublished\":\"2019-09-18T14:42:07+00:00\",\"dateModified\":\"2022-03-04T11:16:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/\"},\"wordCount\":175,\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/EMO-Hannover-RHTC-300x300.jpg\",\"keywords\":[\"EMO Hannover\",\"EMO Hannover 2019\",\"Exposition de Hanovre\",\"foire industrielle\",\"Industrie du travail des m\u00e9taux\",\"machines \u00e0 travailler le m\u00e9tal\",\"presses hydrauliques\",\"Profi Press\",\"Salon d'Hanovre\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/\",\"name\":\"Visiter l'EMO de Hanovre | RHTC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/EMO-Hannover-RHTC-300x300.jpg\",\"datePublished\":\"2019-09-18T14:42:07+00:00\",\"dateModified\":\"2022-03-04T11:16:28+00:00\",\"description\":\"RHTC visite l'EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l'industrie m\u00e9tallurgique !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/EMO-Hannover-RHTC-300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/EMO-Hannover-RHTC-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/visite-de-lemo-hannover-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visiter l&rsquo;EMO de Hanovre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/fr\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\",\"name\":\"RHTC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"caption\":\"RHTC\"},\"sameAs\":[\"http:\\\/\\\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visiter l'EMO de Hanovre | RHTC","description":"RHTC visite l'EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l'industrie m\u00e9tallurgique !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"Visiter l'EMO de Hanovre | RHTC","og_description":"RHTC visite l'EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l'industrie m\u00e9tallurgique !","og_url":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/","og_site_name":"RHTC","article_published_time":"2019-09-18T14:42:07+00:00","article_modified_time":"2022-03-04T11:16:28+00:00","og_image":[{"url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg","type":"","width":"","height":""}],"author":"RHTC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"RHTC","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#article","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/"},"author":{"name":"RHTC","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/person\/fadd73d310be137e9255b99017752b02"},"headline":"Visiter l&rsquo;EMO de Hanovre","datePublished":"2019-09-18T14:42:07+00:00","dateModified":"2022-03-04T11:16:28+00:00","mainEntityOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/"},"wordCount":175,"publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg","keywords":["EMO Hannover","EMO Hannover 2019","Exposition de Hanovre","foire industrielle","Industrie du travail des m\u00e9taux","machines \u00e0 travailler le m\u00e9tal","presses hydrauliques","Profi Press","Salon d'Hanovre"],"articleSection":["Blogs"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/","url":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/","name":"Visiter l'EMO de Hanovre | RHTC","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#primaryimage"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg","datePublished":"2019-09-18T14:42:07+00:00","dateModified":"2022-03-04T11:16:28+00:00","description":"RHTC visite l'EMO 2019 \u00e0 Hanovre cette semaine. Nous nous r\u00e9jouissons de vous rencontrer lors de ce salon professionnel de l'industrie m\u00e9tallurgique !","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#primaryimage","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/09\/EMO-Hannover-RHTC-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/fr\/visite-de-lemo-hannover-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Visiter l&rsquo;EMO de Hanovre"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#website","url":"https:\/\/rhtc-workshoppress.com\/fr\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhtc-workshoppress.com\/fr\/#\/schema\/person\/fadd73d310be137e9255b99017752b02","name":"RHTC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","caption":"RHTC"},"sameAs":["http:\/\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server"]}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/26367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/comments?post=26367"}],"version-history":[{"count":2,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/26367\/revisions"}],"predecessor-version":[{"id":26369,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/posts\/26367\/revisions\/26369"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/media?parent=26367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/categories?post=26367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/fr\/wp-json\/wp\/v2\/tags?post=26367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}