{"id":36122,"date":"2024-09-04T13:33:22","date_gmt":"2024-09-04T13:33:22","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/"},"modified":"2024-09-04T14:24:34","modified_gmt":"2024-09-04T14:24:34","slug":"prensa-hidraulica-de-bastidor-en-c-hecha-a-medida","status":"publish","type":"post","link":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/","title":{"rendered":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb custom_padding=\u00bb0px|||||\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega de una prensa personalizada? Mientras se construye su prensa hidr\u00e1ulica a medida, puede alquilar uno de nuestros modelos est\u00e1ndar que m\u00e1s se ajuste a sus especificaciones. Es una soluci\u00f3n provisional perfecta, \u00a1e incluso ofrecemos la instalaci\u00f3n! \u00a1Una verdadera situaci\u00f3n en la que todos salen ganando! <\/p>\n<p> <\/p>\n<p>Eso es exactamente lo que pens\u00f3 un laboratorio de los Pa\u00edses Bajos cuando encarg\u00f3 una<a href=\"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-hidraulicas-con-cuello-de-cisne\/\" target=\"_blank\" rel=\"noopener\"> prensa de bastidor en C<\/a> personalizada. Mientras tanto, decidieron alquilar nuestro modelo est\u00e1ndar PPC-50 durante tres meses para empezar sus proyectos urgentes de inmediato. Justo la semana pasada, instalamos la prensa en sus instalaciones, y la recogeremos una vez que su prensa hidr\u00e1ulica personalizada de bastidor en C est\u00e9 lista para su entrega. \u00a1Todos contentos!<\/p>\n<p><\/p>\n<p>Solicite presupuesto para una prensa a medida a trav\u00e9s de nuestro sitio web o <a href=\"https:\/\/rhtc-workshoppress.com\/es\/contacto\/\" target=\"_blank\" rel=\"noopener\">p\u00f3ngase en contacto con nosotros<\/a> para conocer las posibilidades de alquilar una de nuestras prensas hidr\u00e1ulicas est\u00e1ndar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36101 size-MB-product-image\" src=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg\" alt=\"Instalaci\u00f3n de una prensa en C en el laboratorio\" width=\"300\" height=\"575\"><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega de una prensa personalizada? Mientras se construye su prensa hidr\u00e1ulica a medida, puede alquilar uno de nuestros modelos est\u00e1ndar que m\u00e1s se ajuste a sus especificaciones. Es una soluci\u00f3n provisional perfecta, \u00a1e incluso ofrecemos la instalaci\u00f3n! \u00a1Una verdadera situaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[704],"tags":[1028],"class_list":["post-36122","post","type-post","status-publish","format-standard","hentry","category-blogs-es","tag-profipress-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC<\/title>\n<meta name=\"description\" content=\"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC\" \/>\n<meta property=\"og:description\" content=\"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T13:33:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T14:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg\" \/>\n<meta name=\"author\" content=\"RHTC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RHTC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/\"},\"author\":{\"name\":\"RHTC\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\"},\"headline\":\"Prensa hidr\u00e1ulica de bastidor en C hecha a medida\",\"datePublished\":\"2024-09-04T13:33:22+00:00\",\"dateModified\":\"2024-09-04T14:24:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/\"},\"wordCount\":249,\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/C-Frame-Press-installation-in-Lab-300x575.jpg\",\"keywords\":[\"profipress\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/\",\"name\":\"Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/C-Frame-Press-installation-in-Lab-300x575.jpg\",\"datePublished\":\"2024-09-04T13:33:22+00:00\",\"dateModified\":\"2024-09-04T14:24:34+00:00\",\"description\":\"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/C-Frame-Press-installation-in-Lab-300x575.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/C-Frame-Press-installation-in-Lab-300x575.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prensa hidr\u00e1ulica de bastidor en C hecha a medida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/person\\\/fadd73d310be137e9255b99017752b02\",\"name\":\"RHTC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g\",\"caption\":\"RHTC\"},\"sameAs\":[\"http:\\\/\\\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC","description":"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/","og_locale":"es_ES","og_type":"article","og_title":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC","og_description":"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.","og_url":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/","og_site_name":"RHTC","article_published_time":"2024-09-04T13:33:22+00:00","article_modified_time":"2024-09-04T14:24:34+00:00","og_image":[{"url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg","type":"","width":"","height":""}],"author":"RHTC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"RHTC","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#article","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/"},"author":{"name":"RHTC","@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/person\/fadd73d310be137e9255b99017752b02"},"headline":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida","datePublished":"2024-09-04T13:33:22+00:00","dateModified":"2024-09-04T14:24:34+00:00","mainEntityOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/"},"wordCount":249,"publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#organization"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg","keywords":["profipress"],"articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/","url":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/","name":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida | RHTC","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#primaryimage"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg","datePublished":"2024-09-04T13:33:22+00:00","dateModified":"2024-09-04T14:24:34+00:00","description":"\u00bfNecesita una prensa hidr\u00e1ulica a medida pero no puede esperar las t\u00edpicas 8-16 semanas de entrega? Puede alquilar uno de nuestros modelos est\u00e1ndar.","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#primaryimage","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/09\/C-Frame-Press-installation-in-Lab-300x575.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/es\/prensa-hidraulica-de-bastidor-en-c-hecha-a-medida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prensa hidr\u00e1ulica de bastidor en C hecha a medida"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/es\/#website","url":"https:\/\/rhtc-workshoppress.com\/es\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/es\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/person\/fadd73d310be137e9255b99017752b02","name":"RHTC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5324327ca8fcd6fef6141df6a5ef04d7fe80555f180040a304c9cf1a058dadd?s=96&d=mm&r=g","caption":"RHTC"},"sameAs":["http:\/\/rhtccac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c77420pre-server"]}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/posts\/36122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/comments?post=36122"}],"version-history":[{"count":2,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/posts\/36122\/revisions"}],"predecessor-version":[{"id":36124,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/posts\/36122\/revisions\/36124"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/media?parent=36122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/categories?post=36122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/tags?post=36122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}