{"id":37291,"date":"2024-11-21T15:29:31","date_gmt":"2024-11-21T15:29:31","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/"},"modified":"2024-11-22T09:13:56","modified_gmt":"2024-11-22T09:13:56","slug":"prensa-de-portico-con-dos-cilindros","status":"publish","type":"page","link":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/","title":{"rendered":"Prensa de p\u00f3rtico con dos cilindros"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbHeader\u00bb module_class=\u00bbheader-top-sub\u00bb _builder_version=\u00bb4.21.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb130deg\u00bb background_color_gradient_stops=\u00bb#352597 0%|#8686FF 100%\u00bb background_color_gradient_start=\u00bb#352597&#8243; background_color_gradient_end=\u00bb#8686FF\u00bb background_image=\u00bbhttps:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/02\/background-header-nologo.png\u00bb parallax=\u00bbon\u00bb custom_padding=\u00bb0||100px||false|false\u00bb custom_padding_tablet=\u00bb100px||100px||true\u00bb custom_padding_phone=\u00bb||||true\u00bb bottom_divider_height=\u00bb250px\u00bb bottom_divider_flip=\u00bbhorizontal\u00bb bottom_divider_height_tablet=\u00bb150px\u00bb bottom_divider_height_phone=\u00bb110px\u00bb bottom_divider_height_last_edited=\u00bbon|phone\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbServices\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0|0px|0|0px|true|false\u00bb bottom_divider_color=\u00bb#0c71c3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_code _builder_version=\u00bb3.14&#8243; global_module=\u00bb339&#8243; global_colors_info=\u00bb{}\u00bb]<span><span><a href=\"https:\/\/rhtc-workshoppress.com\/es\/\">Home<\/a><\/span><\/span>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb4px|0px|0|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text module_class=\u00bbproduct-name\u00bb _builder_version=\u00bb4.21.0&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb2em\u00bb header_2_font=\u00bbRoboto|700|||||||\u00bb header_2_font_size=\u00bb45px\u00bb header_2_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb800px\u00bb max_width_last_edited=\u00bboff|desktop\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb28px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Prensa de p\u00f3rtico con dos cilindros (50 toneladas cada uno)<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb2px|0px|54px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/11\/Straightening-Press-with-two-Portals-and-two-Cylinders.jpg\u00bb alt=\u00bbPrensa de p\u00f3rtico de dos cilindros\u00bb title_text=\u00bbPrensa enderezadora con dos portales y dos cilindros\u00bb show_in_lightbox=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb module_class=\u00bbzoooom\u00bb _builder_version=\u00bb4.21.0&#8243; max_width=\u00bb81{cac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c774}\u00bb max_width_last_edited=\u00bboff|desktop\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Esta prensa de p\u00f3rtico a medida con dos p\u00f3rticos y dos cilindros de 50T est\u00e1 dise\u00f1ada para un cliente que necesitaba una gran superficie para sus tareas de utillaje y prensado. Los cilindros se acercan simult\u00e1neamente y se accionan desde 1 unidad hidr\u00e1ulica. <\/p>\n<p style=\"text-align: justify;\">Podemos entregar nuestras prensas de p\u00f3rtico en varios tonelajes y con varias longitudes de mesa. \u00bfNecesita una mesa m\u00e1s grande, varios portales o cilindros? Para nosotros no hay problema, env\u00edenos un mensaje y le informaremos de todas las posibilidades!<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/rhtc-workshoppress.com\/es\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\">P\u00f3ngase en contacto con nosotros<\/a> para obtener m\u00e1s informaci\u00f3n sobre nuestras prensas de p\u00f3rtico personalizadas. Estamos deseando contarlo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_button button_url=\u00bbhttps:\/\/rhtc-workshoppress.com\/es\/oferta\/\u00bb button_text=\u00bbPedir presupuesto\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbquotation-button\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_bg_color=\u00bb#f48004&#8243; button_bg_color_gradient_direction=\u00bb90deg\u00bb button_bg_color_gradient_stops=\u00bb#00f264 0%|#fcb6ab 100%\u00bb button_bg_color_gradient_start=\u00bb#00f264&#8243; button_bg_color_gradient_end=\u00bb#fcb6ab\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb4px\u00bb button_letter_spacing=\u00bb5px\u00bb button_font=\u00bbRoboto|700||on|||||\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb18px|34px|18px|34px|true|true\u00bb button_letter_spacing_hover=\u00bb5.5px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb5.5px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbServices\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0|0px|0|0px|true|false\u00bb bottom_divider_color=\u00bb#0c71c3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb max_width=\u00bb1440px\u00bb custom_padding=\u00bb27px|0px|0|0px|false|false\u00bb use_custom_width=\u00bbon\u00bb custom_width_px=\u00bb1440px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; header_2_font=\u00bbRoboto||||||||\u00bb header_2_font_size=\u00bb15px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Caracter\u00edsticas de esta prensa de p\u00f3rtico con dos cilindros<br \/><\/strong><\/h2>\n<ul>\n<li>Mesa de 3075 x 996 mm<\/li>\n<li>Tonelaje 50 toneladas por cilindro<\/li>\n<li>Portales m\u00f3viles<\/li>\n<li>Cilindros de movimiento manual<\/li>\n<li>Ambos cilindros est\u00e1n conectados a una herramienta<\/li>\n<li>Regulador de presi\u00f3n y man\u00f3metro<\/li>\n<li>Mando a distancia manual para que el operario pueda desplazarse f\u00e1cilmente por la prensa<\/li>\n<\/ul>\n<p>Vea el v\u00eddeo de esta p\u00e1gina o visite nuestro <a href=\"https:\/\/www.youtube.com\/@rhtcworkshoppresses\" target=\"_blank\" rel=\"noopener\">canal de YouTube<\/a> para ver m\u00e1s v\u00eddeos de nuestras m\u00e1quinas. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/cTQRVOXeOS0&#8243; module_class=\u00bbvideo-homepage\u00bb _builder_version=\u00bb4.21.0&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb prev_background_color=\u00bb#ffffff\u00bb admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb130deg\u00bb background_color_gradient_stops=\u00bb#352597 0%|#8686FF 100%\u00bb background_color_gradient_start=\u00bb#352597&#8243; background_color_gradient_end=\u00bb#8686FF\u00bb background_image=\u00bbhttps:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2018\/09\/below.jpg\u00bb parallax=\u00bbon\u00bb custom_padding=\u00bb9vw||50px||false|false\u00bb custom_padding_tablet=\u00bb100px||100px||true\u00bb custom_padding_phone=\u00bb||||true\u00bb top_divider_style=\u00bbramp\u00bb top_divider_height=\u00bb250px\u00bb top_divider_flip=\u00bbvertical\u00bb top_divider_height_tablet=\u00bb150px\u00bb top_divider_height_phone=\u00bb110px\u00bb top_divider_height_last_edited=\u00bbon|phone\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb4.16&#8243; width=\u00bb89%\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb80%\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb89%\u00bb max_width_tablet=\u00bb80%\u00bb max_width_phone=\u00bb80%\u00bb max_width_last_edited=\u00bbon|desktop\u00bb custom_margin_phone=\u00bb|||\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb|||\u00bb make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbRoboto|700|||||||\u00bb header_2_font_size=\u00bb50px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bbRoboto|700||on|||||\u00bb header_3_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#ffffff\u00bb header_3_font_size=\u00bb24px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb2em\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb850px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb text_font_size_last_edited=\u00bboff|desktop\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb header_3_font_size_tablet=\u00bb16px\u00bb header_3_font_size_phone=\u00bb14px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><\/h3>\n<h2>&#8216; PRESIONAR PARA IMPRESIONAR &#8216;<\/h2>\n<h3>Sigamos en contacto<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/rhtc-workshoppress.com\/es\/contacto\/\u00bb button_text=\u00bbCont\u00e1ctenos\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_bg_color=\u00bb#f48004&#8243; button_bg_color_gradient_direction=\u00bb90deg\u00bb button_bg_color_gradient_stops=\u00bb#00f264 0%|#fcb6ab 100%\u00bb button_bg_color_gradient_start=\u00bb#00f264&#8243; button_bg_color_gradient_end=\u00bb#fcb6ab\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb4px\u00bb button_letter_spacing=\u00bb5px\u00bb button_font=\u00bbRoboto|700||on|||||\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb18px|34px|18px|34px|true|true\u00bb button_letter_spacing_hover=\u00bb5.5px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb5.5px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span><span><a href=\"https:\/\/rhtc-workshoppress.com\/es\/\">Home<\/a><\/span><\/span>Prensa de p\u00f3rtico con dos cilindros (50 toneladas cada uno)Esta prensa de p\u00f3rtico a medida con dos p\u00f3rticos y dos cilindros de 50T est\u00e1 dise\u00f1ada para un cliente que necesitaba una gran superficie para sus tareas de utillaje y prensado. Los cilindros se acercan simult\u00e1neamente y se accionan desde 1 unidad hidr\u00e1ulica. Podemos entregar nuestras [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":27070,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-37291","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC<\/title>\n<meta name=\"description\" content=\"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente &amp; prensan 50 toneladas cada uno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC\" \/>\n<meta property=\"og:description\" content=\"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente &amp; prensan 50 toneladas cada uno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T09:13:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/prensa-de-portico-con-dos-cilindros\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/prensa-de-portico-con-dos-cilindros\\\/\",\"name\":\"Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#website\"},\"datePublished\":\"2024-11-21T15:29:31+00:00\",\"dateModified\":\"2024-11-22T09:13:56+00:00\",\"description\":\"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente & prensan 50 toneladas cada uno\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/prensa-de-portico-con-dos-cilindros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/prensa-de-portico-con-dos-cilindros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/prensa-de-portico-con-dos-cilindros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prensas a medida\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/productos\\\/prensas-a-medida\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Prensa de p\u00f3rtico con dos cilindros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC","description":"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente & prensan 50 toneladas cada uno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/","og_locale":"es_ES","og_type":"article","og_title":"Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC","og_description":"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente & prensan 50 toneladas cada uno","og_url":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/","og_site_name":"RHTC","article_modified_time":"2024-11-22T09:13:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/","url":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/","name":"Prensa de p\u00f3rtico con dos cilindros | Profi Press | RHTC","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#website"},"datePublished":"2024-11-21T15:29:31+00:00","dateModified":"2024-11-22T09:13:56+00:00","description":"Recientemente hemos entregado esta prensa de p\u00f3rtico con dos cilindros a uno de nuestros clientes. Los cilindros se acercan simult\u00e1neamente & prensan 50 toneladas cada uno","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/prensa-de-portico-con-dos-cilindros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/rhtc-workshoppress.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Prensas a medida","item":"https:\/\/rhtc-workshoppress.com\/es\/productos\/prensas-a-medida\/"},{"@type":"ListItem","position":4,"name":"Prensa de p\u00f3rtico con dos cilindros"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/es\/#website","url":"https:\/\/rhtc-workshoppress.com\/es\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/es\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/pages\/37291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/comments?post=37291"}],"version-history":[{"count":2,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/pages\/37291\/revisions"}],"predecessor-version":[{"id":37293,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/pages\/37291\/revisions\/37293"}],"up":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/pages\/27070"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/es\/wp-json\/wp\/v2\/media?parent=37291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}