{"id":4446,"date":"2019-02-06T13:26:31","date_gmt":"2019-02-06T13:26:31","guid":{"rendered":"https:\/\/rhtc-workshoppress.com\/ppcf-150\/"},"modified":"2024-10-14T07:29:44","modified_gmt":"2024-10-14T07:29:44","slug":"ppcu-hs-150","status":"publish","type":"page","link":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/","title":{"rendered":"PPCU-HS-150"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Header&#8220; module_class=&#8220;header-top-sub&#8220; _builder_version=&#8220;4.16&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_direction=&#8220;130deg&#8220; background_color_gradient_stops=&#8220;#352597 0%|#8686FF 100%&#8220; background_color_gradient_start=&#8220;#352597&#8243; background_color_gradient_end=&#8220;#8686FF&#8220; background_image=&#8220;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/02\/background-header-nologo.png&#8220; parallax=&#8220;on&#8220; custom_padding=&#8220;0||100px||false|false&#8220; custom_padding_tablet=&#8220;100px||100px||true&#8220; custom_padding_phone=&#8220;||||true&#8220; bottom_divider_height=&#8220;250px&#8220; bottom_divider_flip=&#8220;horizontal&#8220; bottom_divider_height_tablet=&#8220;150px&#8220; bottom_divider_height_phone=&#8220;110px&#8220; bottom_divider_height_last_edited=&#8220;on|phone&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Services&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0|0px|0|0px|true|false&#8220; bottom_divider_color=&#8220;#0c71c3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_code _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<span><span><a href=\"https:\/\/rhtc-workshoppress.com\/de\/\">Home<\/a><\/span><\/span>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;4px|0px|27px|0px|false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text module_class=&#8220;product-name&#8220; _builder_version=&#8220;4.21.0&#8243; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;2em&#8220; header_font=&#8220;Roboto||||||||&#8220; header_font_size=&#8220;45px&#8220; header_line_height=&#8220;1.3em&#8220; header_2_font=&#8220;Roboto|700|||||||&#8220; header_2_font_size=&#8220;45px&#8220; header_2_line_height=&#8220;1.2em&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;800px&#8220; max_width_last_edited=&#8220;off|desktop&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;|||&#8220; header_2_font_size_tablet=&#8220;35px&#8220; header_2_font_size_phone=&#8220;28px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>C-Rahmen Presse mit hohen Geschwindigkeiten: PPCU-HS-150<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; specialty=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;2px|0px|54px|0px|false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/C-Frame-Press-Profi-Press-PPCU-HS-Model-scaled.jpg&#8220; alt=&#8220;C-Rahmen Presse &#8211; Profi Press&#8220; title_text=&#8220;C-Frame Presse &#8211; Profi Press&#8220; show_in_lightbox=&#8220;on&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; module_class=&#8220;zoooom&#8220; _builder_version=&#8220;4.21.0&#8243; max_width=&#8220;65{cac4c9dc6722fe84e5c9b5f9db854df7049fc70354449285581c113afa32c774}&#8220; max_width_last_edited=&#8220;off|desktop&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; specialty_columns=&#8220;2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p style=\"text-align: justify;\">Diese 150 Tonnen C-Rahmen Presse mit hohen Geschwindigkeiten ist geeignet f\u00fcr Press-, Stanz- und Formaufgaben in mittleren und gro\u00dfen St\u00fcckzahlen. Auch zum Einbau in automatisierte Produktionslinien geeignet.<\/p>\n<p style=\"text-align: justify;\">Produziert mit einem oberen und unteren Tisch mit T-Nuten. Der Obertisch sorgt durch vier zylindrische Seitenf\u00fchrungen f\u00fcr eine perfekte Ausrichtung. Ausgestattet mit einem Hauptzylinder und zwei Seitenzylindern, um die hohen Geschwindigkeiten zu erreichen. Die Hydraulikeinheit ist standardm\u00e4\u00dfig mit einem Luft-\u00d6l-K\u00fchlsystem ausgestattet.<\/p>\n<p style=\"text-align: justify;\">Wir produzieren diese C-Rahmen Presse mit hohen Geschwindigkeiten mit \u00fcber ein Bedienfeld mit einer Siemens-SPS mit Touchscreen. Das Steuerungssystem erm\u00f6glicht die Programmierung von Presskraft, Zylinderhub, Geschwindigkeit und Druckzeit.  Es verf\u00fcgt \u00fcber eine Speicherkapazit\u00e4t zum Speichern von bis zu 100 verschiedenen Arbeitszyklen.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Unsere C-Gestell-Pressen<\/a> werden in Europa hergestellt und gem\u00e4\u00df der aktuellsten CE-Norm ausgeliefert. Hohe Qualit\u00e4t garantiert!<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_button button_url=&#8220;https:\/\/rhtc-workshoppress.com\/de\/angebot\/&#8220; button_text=&#8220;Angebot anfordern&#8220; button_alignment=&#8220;center&#8220; module_class=&#8220;quotation-button&#8220; _builder_version=&#8220;4.16&#8243; custom_button=&#8220;on&#8220; button_text_size=&#8220;13px&#8220; button_bg_color=&#8220;#f48004&#8243; button_bg_color_gradient_direction=&#8220;90deg&#8220; button_bg_color_gradient_stops=&#8220;#00f264 0%|#fcb6ab 100%&#8220; button_bg_color_gradient_start=&#8220;#00f264&#8243; button_bg_color_gradient_end=&#8220;#fcb6ab&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;rgba(0,0,0,0)&#8220; button_border_radius=&#8220;4px&#8220; button_letter_spacing=&#8220;5px&#8220; button_font=&#8220;Roboto|700||on|||||&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;18px|34px|18px|34px|true|true&#8220; button_letter_spacing_hover=&#8220;5.5px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_text_size__hover_enabled=&#8220;off&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_text_color__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_border_width__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_border_color__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;off&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_border_radius__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;off&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_letter_spacing__hover_enabled=&#8220;on&#8220; button_letter_spacing__hover=&#8220;5.5px&#8220; button_one_letter_spacing__hover_enabled=&#8220;off&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_bg_color__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;off&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner type=&#8220;1_3&#8243; saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/NC-control-on-a-HMI-arm-575&#215;384.jpg&#8220; alt=&#8220;NC-Steuerung auf einem HMI-Arm&#8220; show_in_lightbox=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8220;1_3&#8243; saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/Upper-Table-with-Lateral-Guides-and-Auxiliary-Cylinder-575&#215;384.jpg&#8220; alt=&#8220;Obertisch mit seitlichen F\u00fchrungen und Hilfszylindern&#8220; show_in_lightbox=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8220;1_3&#8243; saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Services&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0|0px|0|0px|true|false&#8220; bottom_divider_color=&#8220;#0c71c3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; max_width=&#8220;1440px&#8220; custom_padding=&#8220;27px|0px|0|0px|false|false&#8220; use_custom_width=&#8220;on&#8220; custom_width_px=&#8220;1440px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; header_2_font=&#8220;Roboto||||||||&#8220; header_2_font_size=&#8220;15px&#8220; header_2_line_height=&#8220;1.2em&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2><strong>Technische Daten dieser PPCU-HS-150<\/strong><\/h2>\n<ul>\n<li>Presskraft [tn]: 150<\/li>\n<li>Motorleistung [kw]: 7.5<\/li>\n<li>Ausladung [mm]: 380<\/li>\n<li>Arbeitsgeschwindigkeit [mm\/sec]: 4.7<\/li>\n<li>Ann\u00e4herungsgeschwindigkeit [mm\/sec]: 73<\/li>\n<li>R\u00fccklaufgeschwindigkeit [mm\/sec]: 110<\/li>\n<li>Max. Druck [bar]: 250<\/li>\n<li>Kolbenhub [mm]: 400<\/li>\n<li>Untere Tischgr\u00f6\u00dfe [mm]: 850 x 600 x 110<\/li>\n<li>Obere Tischgr\u00f6\u00dfe [mm]: 720 x 460 x 110<\/li>\n<li>Max. Einbauh\u00f6he [mm]: 600<\/li>\n<li>Tischh\u00f6he [mm]: 875<\/li>\n<li>Gesamtl\u00e4nge [mm]: 2000<\/li>\n<li>Gesamtbreite [mm]: 1800<\/li>\n<li>Totale hoogte [mm]: 2750<\/li>\n<li>Gewicht [kg]: 5100<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; header_2_font_size=&#8220;15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2><strong>Merkmale dieses C-Rahmen Presse mit hohen Geschwindigkeiten<\/strong><\/h2>\n<ul>\n<li>Ausgestattet mit einem Ober- und Untertisch mit T-Nuten (DIN-650); Werkzeuge k\u00f6nnen einfach auf den Tischen befestigt werden<\/li>\n<li>Perfekte Ausrichtung dank vier seitlichen F\u00fchrungen f\u00fcr den oberen Tisch<\/li>\n<li>Ein Hauptzylinder und zwei Seitenzylinder f\u00fcr hohe Geschwindigkeiten<\/li>\n<li>Zwei seitliche Schutzgitter (zum \u00d6ffnen \/ nach hinten zu schieben) mit Sicherheitslichtschranken der Stufe IV an der Vorderseite<\/li>\n<li>Siemens-SPS-Bedienfeld zum Programmieren von Leistung, Zylinderhub und Druckzeit, zum Ausw\u00e4hlen des Arbeitsmodus und der Zylindergeschwindigkeiten und mit der M\u00f6glichkeit, bis zu 100 Arbeitszyklen zu speichern<\/li>\n<li>Bedienung \u00fcber ein Fu\u00dfpedal<\/li>\n<\/ul>\n<p><a href=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-36644 size-large\" src=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg\" alt=\"Hydraulische C-Rahmenpresse \u2013 Hohe Geschwindigkeiten \u2013 PPCU-HS-Modell\" width=\"683\" height=\"1024\"><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;||||||||&#8220; ul_font=&#8220;||||||||&#8220; ol_font=&#8220;||||||||&#8220; header_line_height=&#8220;1.2em&#8220; header_2_font=&#8220;Roboto||||||||&#8220; header_2_font_size=&#8220;15px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2><strong>Optionales Zubeh\u00f6r<\/strong><\/h2>\n<ul>\n<li>An Ihre Anforderungen angepasste Geometrie (zum Beispiel gr\u00f6\u00dfere Tische, eine gr\u00f6\u00dfere Einbauh\u00f6he oder ein gr\u00f6\u00dferer Kolbenhub f\u00fcr diese hydraulische C-Rahmen Presse)<\/li>\n<li>Auf Ihre Anforderungen angepasste Software<\/li>\n<li>Hydraulischer Auswerfer<\/li>\n<li>Hydraulikkissen<\/li>\n<li>Anpassungen an die Robotik<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Standard oder Sonderanfertigung, unsere C-Gestell Pressen sind echte Bestseller!<\/em><\/p>\n<p>Geeignet f\u00fcr viele verschiedene Pressarbeiten. Auf unserem <a href=\"\" target=\"\" rel=\"noopener\">YouTube-Kanal<\/a> finden Sie viele Videos unserer Hydraulikpressen, darunter auch diese C-Rahmenpresse. Die M\u00f6glichkeiten zur Herstellung unserer Hydraulikpressen sind endlos, also teilen Sie uns Ihre Anforderungen mit, wir freuen uns, Ihnen bei Ihrem n\u00e4chsten Projekt zu helfen.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|desktop&#8220; prev_background_color=&#8220;#ffffff&#8220; admin_label=&#8220;Footer&#8220; _builder_version=&#8220;4.16&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_direction=&#8220;130deg&#8220; background_color_gradient_stops=&#8220;#352597 0%|#8686FF 100%&#8220; background_color_gradient_start=&#8220;#352597&#8243; background_color_gradient_end=&#8220;#8686FF&#8220; background_image=&#8220;https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2018\/09\/below.jpg&#8220; parallax=&#8220;on&#8220; custom_padding=&#8220;9vw||50px||false|false&#8220; custom_padding_tablet=&#8220;100px||100px||true&#8220; custom_padding_phone=&#8220;||||true&#8220; top_divider_style=&#8220;ramp&#8220; top_divider_height=&#8220;250px&#8220; top_divider_flip=&#8220;vertical&#8220; top_divider_height_tablet=&#8220;150px&#8220; top_divider_height_phone=&#8220;110px&#8220; top_divider_height_last_edited=&#8220;on|phone&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row module_class=&#8220; et_pb_row_fullwidth&#8220; _builder_version=&#8220;4.16&#8243; width=&#8220;89%&#8220; width_tablet=&#8220;80%&#8220; width_phone=&#8220;80%&#8220; width_last_edited=&#8220;on|desktop&#8220; max_width=&#8220;89%&#8220; max_width_tablet=&#8220;80%&#8220; max_width_phone=&#8220;80%&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin_phone=&#8220;|||&#8220; custom_margin_last_edited=&#8220;off|desktop&#8220; custom_padding=&#8220;|||&#8220; make_fullwidth=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; text_font=&#8220;||||||||&#8220; header_font=&#8220;||||||||&#8220; header_2_font=&#8220;Roboto|700|||||||&#8220; header_2_font_size=&#8220;50px&#8220; header_2_line_height=&#8220;1.4em&#8220; header_3_font=&#8220;Roboto|700||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;24px&#8220; header_3_letter_spacing=&#8220;5px&#8220; header_3_line_height=&#8220;2em&#8220; text_orientation=&#8220;center&#8220; background_layout=&#8220;dark&#8220; max_width=&#8220;850px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;|||&#8220; text_font_size_last_edited=&#8220;off|desktop&#8220; header_2_font_size_tablet=&#8220;40px&#8220; header_2_font_size_phone=&#8220;32px&#8220; header_2_font_size_last_edited=&#8220;on|desktop&#8220; header_3_font_size_tablet=&#8220;16px&#8220; header_3_font_size_phone=&#8220;14px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3><\/h3>\n<h2>\u2018 PRESS TO IMPRESS \u2018<\/h2>\n<h3>Lass uns in Kontakt bleiben<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/rhtc-workshoppress.com\/de\/kontakt\/&#8220; button_text=&#8220;Kontaktieren Sie uns&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; custom_button=&#8220;on&#8220; button_text_size=&#8220;13px&#8220; button_bg_color=&#8220;#f48004&#8243; button_bg_color_gradient_direction=&#8220;90deg&#8220; button_bg_color_gradient_stops=&#8220;#00f264 0%|#fcb6ab 100%&#8220; button_bg_color_gradient_start=&#8220;#00f264&#8243; button_bg_color_gradient_end=&#8220;#fcb6ab&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;rgba(0,0,0,0)&#8220; button_border_radius=&#8220;4px&#8220; button_letter_spacing=&#8220;5px&#8220; button_font=&#8220;Roboto|700||on|||||&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;18px|34px|18px|34px|true|true&#8220; button_letter_spacing_hover=&#8220;5.5px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_text_size__hover_enabled=&#8220;off&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_text_color__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_border_width__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_border_color__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;off&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_border_radius__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;off&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_letter_spacing__hover_enabled=&#8220;on&#8220; button_letter_spacing__hover=&#8220;5.5px&#8220; button_one_letter_spacing__hover_enabled=&#8220;off&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_bg_color__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;off&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span><span><a href=\"https:\/\/rhtc-workshoppress.com\/de\/\">Home<\/a><\/span><\/span>C-Rahmen Presse mit hohen Geschwindigkeiten: PPCU-HS-150Diese 150 Tonnen C-Rahmen Presse mit hohen Geschwindigkeiten ist geeignet f\u00fcr Press-, Stanz- und Formaufgaben in mittleren und gro\u00dfen St\u00fcckzahlen. Auch zum Einbau in automatisierte Produktionslinien geeignet. Produziert mit einem oberen und unteren Tisch mit T-Nuten. Der Obertisch sorgt durch vier zylindrische Seitenf\u00fchrungen f\u00fcr eine perfekte Ausrichtung. Ausgestattet mit einem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4475,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-4446","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC<\/title>\n<meta name=\"description\" content=\"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC\" \/>\n<meta property=\"og:description\" content=\"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/\" \/>\n<meta property=\"og:site_name\" content=\"RHTC\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T07:29:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/\",\"name\":\"C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg\",\"datePublished\":\"2019-02-06T13:26:31+00:00\",\"dateModified\":\"2024-10-14T07:29:44+00:00\",\"description\":\"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/ppcu-hs-150\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C-Rahmen Pressen\",\"item\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/produkte\\\/c-rahmen-pressen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PPCU-HS-150\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/\",\"name\":\"RHTC\",\"description\":\"Profi Press, high quality hydraulic presses\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#organization\",\"name\":\"RHTC B.V.\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-wit-scaled.jpg\",\"width\":3000,\"height\":2250,\"caption\":\"RHTC B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/rhtc-workshoppress.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC","description":"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/","og_locale":"de_DE","og_type":"article","og_title":"C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC","og_description":"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!","og_url":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/","og_site_name":"RHTC","article_modified_time":"2024-10-14T07:29:44+00:00","og_image":[{"url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/","url":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/","name":"C-Rahmen Presse mit hohen Geschwindigkeiten | PPCU-HS-150 | Profi Press | RHTC","isPartOf":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/#primaryimage"},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/#primaryimage"},"thumbnailUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg","datePublished":"2019-02-06T13:26:31+00:00","dateModified":"2024-10-14T07:29:44+00:00","description":"Diese C-Rahmen Presse mit hohen Geschwindigkeiten verf\u00fcgt \u00fcber eine NC-Steuerung von Siemens f\u00fcr eine einfache, schnelle und pr\u00e4zise Bedienung. Hohe Qualit\u00e4t garantiert!","breadcrumb":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/#primaryimage","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2024\/10\/PPCU-HS-100-with-protection-screens-backwards-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/ppcu-hs-150\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhtc-workshoppress.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"C-Rahmen Pressen","item":"https:\/\/rhtc-workshoppress.com\/de\/produkte\/c-rahmen-pressen\/"},{"@type":"ListItem","position":4,"name":"PPCU-HS-150"}]},{"@type":"WebSite","@id":"https:\/\/rhtc-workshoppress.com\/de\/#website","url":"https:\/\/rhtc-workshoppress.com\/de\/","name":"RHTC","description":"Profi Press, high quality hydraulic presses","publisher":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhtc-workshoppress.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rhtc-workshoppress.com\/de\/#organization","name":"RHTC B.V.","url":"https:\/\/rhtc-workshoppress.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rhtc-workshoppress.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","contentUrl":"https:\/\/rhtc-workshoppress.com\/wp-content\/uploads\/2019\/04\/Logo-wit-scaled.jpg","width":3000,"height":2250,"caption":"RHTC B.V."},"image":{"@id":"https:\/\/rhtc-workshoppress.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/pages\/4446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/comments?post=4446"}],"version-history":[{"count":15,"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/pages\/4446\/revisions"}],"predecessor-version":[{"id":36803,"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/pages\/4446\/revisions\/36803"}],"up":[{"embeddable":true,"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/pages\/4475"}],"wp:attachment":[{"href":"https:\/\/rhtc-workshoppress.com\/de\/wp-json\/wp\/v2\/media?parent=4446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}